{"id":22,"count":33,"description":"LED Buitenverlichting is ideaal voor het verlichten van je tuin, balkon of terras en zijn verkrijgbaar in allerlei vormen, speciaal geschikt voor de verschillende functies. Alle tuinlampen en buitenlampen zijn beschermd tegen water en stof, dit wordt aangeduid in IP-waarden.","link":"https:\/\/ledgoeroe.nl\/de\/led-buitenverlichting\/","name":"LED Buitenverlichting","slug":"led-buitenverlichting","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":19,"acf":[],"yoast_head":"<title>LED Buitenverlichting | LED Goeroe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ledgoeroe.nl\/de\/led-buitenverlichting\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LED Buitenverlichting\" \/>\n<meta property=\"og:description\" content=\"LED Buitenverlichting is ideaal voor het verlichten van je tuin, balkon of terras en zijn verkrijgbaar in allerlei vormen, speciaal geschikt voor de verschillende functies. Alle tuinlampen en buitenlampen zijn beschermd tegen water en stof, dit wordt aangeduid in IP-waarden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ledgoeroe.nl\/de\/led-buitenverlichting\/\" \/>\n<meta property=\"og:site_name\" content=\"LED Goeroe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ledgoeroe\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ledgoeroe.nl\\\/led-buitenverlichting\\\/\",\"url\":\"https:\\\/\\\/ledgoeroe.nl\\\/led-buitenverlichting\\\/\",\"name\":\"LED Buitenverlichting | LED Goeroe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ledgoeroe.nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ledgoeroe.nl\\\/led-buitenverlichting\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ledgoeroe.nl\\\/led-buitenverlichting\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ledgoeroe.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LED Buitenverlichting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ledgoeroe.nl\\\/#website\",\"url\":\"https:\\\/\\\/ledgoeroe.nl\\\/\",\"name\":\"LED Goeroe\",\"description\":\"D\u00e9 specialist in LED-verlichting\",\"publisher\":{\"@id\":\"https:\\\/\\\/ledgoeroe.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ledgoeroe.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ledgoeroe.nl\\\/#organization\",\"name\":\"LED Goeroe\",\"url\":\"https:\\\/\\\/ledgoeroe.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ledgoeroe.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ledgoeroe.nl\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ledgoeroe-logo.png\",\"contentUrl\":\"https:\\\/\\\/ledgoeroe.nl\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ledgoeroe-logo.png\",\"width\":370,\"height\":70,\"caption\":\"LED Goeroe\"},\"image\":{\"@id\":\"https:\\\/\\\/ledgoeroe.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ledgoeroe\",\"https:\\\/\\\/x.com\\\/ledgoeroe\",\"https:\\\/\\\/nl.linkedin.com\\\/in\\\/bj\u00f6rn-tolner-58a74063\"]}]}<\/script>","yoast_head_json":{"title":"LED Buitenverlichting | LED Goeroe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ledgoeroe.nl\/de\/led-buitenverlichting\/","og_locale":"de_DE","og_type":"article","og_title":"LED Buitenverlichting","og_description":"LED Buitenverlichting is ideaal voor het verlichten van je tuin, balkon of terras en zijn verkrijgbaar in allerlei vormen, speciaal geschikt voor de verschillende functies. Alle tuinlampen en buitenlampen zijn beschermd tegen water en stof, dit wordt aangeduid in IP-waarden.","og_url":"https:\/\/ledgoeroe.nl\/de\/led-buitenverlichting\/","og_site_name":"LED Goeroe","twitter_card":"summary_large_image","twitter_site":"@ledgoeroe","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ledgoeroe.nl\/led-buitenverlichting\/","url":"https:\/\/ledgoeroe.nl\/led-buitenverlichting\/","name":"LED Buitenverlichting | LED Goeroe","isPartOf":{"@id":"https:\/\/ledgoeroe.nl\/#website"},"breadcrumb":{"@id":"https:\/\/ledgoeroe.nl\/led-buitenverlichting\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/ledgoeroe.nl\/led-buitenverlichting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ledgoeroe.nl\/"},{"@type":"ListItem","position":2,"name":"LED Buitenverlichting"}]},{"@type":"WebSite","@id":"https:\/\/ledgoeroe.nl\/#website","url":"https:\/\/ledgoeroe.nl\/","name":"LED Goeroe","description":"D\u00e9 specialist in LED-verlichting","publisher":{"@id":"https:\/\/ledgoeroe.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ledgoeroe.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ledgoeroe.nl\/#organization","name":"LED Goeroe","url":"https:\/\/ledgoeroe.nl\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ledgoeroe.nl\/#\/schema\/logo\/image\/","url":"https:\/\/ledgoeroe.nl\/wp-content\/uploads\/2018\/11\/ledgoeroe-logo.png","contentUrl":"https:\/\/ledgoeroe.nl\/wp-content\/uploads\/2018\/11\/ledgoeroe-logo.png","width":370,"height":70,"caption":"LED Goeroe"},"image":{"@id":"https:\/\/ledgoeroe.nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ledgoeroe","https:\/\/x.com\/ledgoeroe","https:\/\/nl.linkedin.com\/in\/bj\u00f6rn-tolner-58a74063"]}]}},"_links":{"self":[{"href":"https:\/\/ledgoeroe.nl\/de\/wp-json\/wp\/v2\/product_cat\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ledgoeroe.nl\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ledgoeroe.nl\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/ledgoeroe.nl\/de\/wp-json\/wp\/v2\/product?product_cat=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}